{"id":2082,"date":"2021-07-01T10:00:09","date_gmt":"2021-07-01T08:00:09","guid":{"rendered":"https:\/\/chloro-fil.fr\/lesnidsdechlorofil\/?p=2082"},"modified":"2021-06-23T15:21:49","modified_gmt":"2021-06-23T13:21:49","slug":"et-si-vous-rassembliez-vos-collaborateurs-a-8m-de-haut-le-temps-dun-seminaire","status":"publish","type":"post","link":"https:\/\/chloro-fil.fr\/lesnidsdechlorofil\/et-si-vous-rassembliez-vos-collaborateurs-a-8m-de-haut-le-temps-dun-seminaire\/","title":{"rendered":"Et si vous rassembliez vos collaborateurs \u00e0 8m de haut le temps d\u2019un s\u00e9minaire ?"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2082\" class=\"elementor elementor-2082\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e32c5cd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e32c5cd\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-82dc710\" data-id=\"82dc710\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fdf786c elementor-widget elementor-widget-heading\" data-id=\"fdf786c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Et si vous rassembliez vos collaborateurs \u00e0 8m de haut le temps d\u2019un s\u00e9minaire ?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-992958a elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"992958a\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-18553bb\" data-id=\"18553bb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4a88996 elementor-widget elementor-widget-text-editor\" data-id=\"4a88996\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Au c\u0153ur de la for\u00eat de <strong>Phalempin<\/strong>, au d\u00e9tour d\u2019une balade \ud83d\udeb6\u200d\u2640, vous pourrez apercevoir des cabanes perch\u00e9es. Ce sont <a href=\"https:\/\/chloro-fil.fr\/lesnidsdechlorofil\/\"><strong>les Nids de Chlorofil<\/strong><\/a> \ud83c\udfe1.<\/p><p>Une des<a href=\"https:\/\/chloro-fil.fr\/lesnidsdechlorofil\/cabanes\/\"><strong> trois cabanes<\/strong> <\/a>est am\u00e9nageable pour accueillir les <a href=\"https:\/\/chloro-fil.fr\/lesnidsdechlorofil\/seminaire\/\"><strong>s\u00e9minaires<\/strong><\/a> d\u2019entreprise !<\/p><p>Nous vous proposons de faire d\u00e9couvrir le lieu \u00e0 vos <strong>collaborateurs<\/strong>, le temps d\u2019une <strong>r\u00e9union<\/strong> qui plus est, <strong>insolite<\/strong> ! C\u2019est le mot pour d\u00e9crire cette exp\u00e9rience.<\/p><p>Nous vous laissons <strong>d\u00e9briefer<\/strong> le temps qu\u2019il vous faut afin de souder des liens entre les collaborateurs.<\/p><p>Nous mettons \u00e0 votre <strong>disposition<\/strong> :<br \/>\ud83d\udc49Une <strong>cabane<\/strong> dans les arbres pour la journ\u00e9e<br \/>\ud83d\udc49 Avec tables, chaises, vid\u00e9o projecteur et enceinte pour la r\u00e9union<br \/>\ud83d\udc49 Un <strong>petit d\u00e9jeuner<\/strong> d\u2019accueil<br \/>\ud83d\udc49 Un <strong>barbecue<\/strong> le midi<br \/>\ud83d\udc49 Une <strong>pause<\/strong> sucr\u00e9e l\u2019apr\u00e8s-midi<\/p><p>Vous pouvez composer votre s\u00e9minaire comme vous l\u2019entendez. Pour vous challenger, nous pouvons aussi vous proposer :<br \/>\ud83d\udc49 Une activit\u00e9 de <strong>parcours<\/strong> acrobatiques en hauteur<br \/>\ud83d\udc49 Une <strong>course d\u2019orientation<\/strong> au coeur de la for\u00eat domaniale<br \/>\ud83d\udc49 Une balade en<a href=\"http:\/\/lille.trott-aventure.com\/\" target=\"_blank\" rel=\"noopener\"><strong> trottinette \u00e9lectrique<\/strong> <\/a>tout-terrain<\/p><p>N\u2019h\u00e9sitez pas \u00e0 demander un <a href=\"https:\/\/chloro-fil.fr\/lesnidsdechlorofil\/reservation\/\"><strong>devis<\/strong><\/a>, il est gratuit, afin de pouvoir venir profiter pleinement des activit\u00e9s chez <a href=\"https:\/\/chloro-fil.fr\/parcours-branches\/\" target=\"_blank\" rel=\"noopener\"><strong>Chlorofil Accrobranche<\/strong> <\/a>x <strong>Les Nids de Chlorofil<\/strong> ! \ud83c\udf3f<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-203f3d1 elementor-share-buttons--view-icon elementor-share-buttons--shape-circle elementor-share-buttons--skin-gradient elementor-grid-0 elementor-share-buttons--color-official elementor-widget elementor-widget-share-buttons\" data-id=\"203f3d1\" data-element_type=\"widget\" data-widget_type=\"share-buttons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_facebook\" role=\"button\" tabindex=\"0\" aria-label=\"Share on facebook\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-facebook\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_linkedin\" role=\"button\" tabindex=\"0\" aria-label=\"Share on linkedin\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-linkedin\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e9bb9f5 elementor-align-center elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"e9bb9f5\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"https:\/\/chloro-fil.fr\/lesnidsdechlorofil\/actualites\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">RETOUR<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Au c\u0153ur de la for\u00eat de Phalempin, au d\u00e9tour d\u2019une balade \ud83d\udeb6\u200d\u2640, vous pourrez apercevoir des cabanes perch\u00e9es. Ce sont les Nids de Chlorofil \ud83c\udfe1. Une des trois cabanes est am\u00e9nageable pour accueillir les s\u00e9minaires d\u2019entreprise ! Nous vous proposons de faire d\u00e9couvrir le lieu \u00e0 vos collaborateurs, le temps d\u2019une r\u00e9union qui plus est, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":765,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"elementor_header_footer","format":"standard","meta":{"_seopress_robots_primary_cat":"none","_seopress_titles_title":"Et si vous rassembliez vos collaborateurs \u00e0 8m de haut le temps d\u2019un s\u00e9minaire ? ","_seopress_titles_desc":"Prenez de la hauteur et venez profiter d&#039;un moment unique entre collaborateurs ! A 8m de haut, sensation et frissons garantis","_seopress_robots_index":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2082","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe"],"jetpack_featured_media_url":"https:\/\/chloro-fil.fr\/lesnidsdechlorofil\/wp-content\/uploads\/2020\/04\/vue-de-la-cab-2-et-la-6-en-fond.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/chloro-fil.fr\/lesnidsdechlorofil\/wp-json\/wp\/v2\/posts\/2082","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chloro-fil.fr\/lesnidsdechlorofil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chloro-fil.fr\/lesnidsdechlorofil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chloro-fil.fr\/lesnidsdechlorofil\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/chloro-fil.fr\/lesnidsdechlorofil\/wp-json\/wp\/v2\/comments?post=2082"}],"version-history":[{"count":9,"href":"https:\/\/chloro-fil.fr\/lesnidsdechlorofil\/wp-json\/wp\/v2\/posts\/2082\/revisions"}],"predecessor-version":[{"id":2092,"href":"https:\/\/chloro-fil.fr\/lesnidsdechlorofil\/wp-json\/wp\/v2\/posts\/2082\/revisions\/2092"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chloro-fil.fr\/lesnidsdechlorofil\/wp-json\/wp\/v2\/media\/765"}],"wp:attachment":[{"href":"https:\/\/chloro-fil.fr\/lesnidsdechlorofil\/wp-json\/wp\/v2\/media?parent=2082"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chloro-fil.fr\/lesnidsdechlorofil\/wp-json\/wp\/v2\/categories?post=2082"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chloro-fil.fr\/lesnidsdechlorofil\/wp-json\/wp\/v2\/tags?post=2082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}