{"id":2235,"date":"2022-01-01T10:00:07","date_gmt":"2022-01-01T09:00:07","guid":{"rendered":"https:\/\/chloro-fil.fr\/lesnidsdechlorofil\/?p=2235"},"modified":"2021-12-14T17:09:15","modified_gmt":"2021-12-14T16:09:15","slug":"place-a-la-fete-de-lamour-quoi-regarder-au-chaud-sous-la-couette","status":"publish","type":"post","link":"https:\/\/chloro-fil.fr\/lesnidsdechlorofil\/place-a-la-fete-de-lamour-quoi-regarder-au-chaud-sous-la-couette\/","title":{"rendered":"Place \u00e0 la f\u00eate de l\u2019amour : Quoi regarder au chaud sous la couette ?"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2235\" class=\"elementor elementor-2235\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e32c5cd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e32c5cd\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-82dc710\" data-id=\"82dc710\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fdf786c elementor-widget elementor-widget-heading\" data-id=\"fdf786c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Place \u00e0 la f\u00eate de l\u2019amour : Quoi regarder au chaud sous la couette ?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-992958a elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"992958a\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-18553bb\" data-id=\"18553bb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4a88996 elementor-widget elementor-widget-text-editor\" data-id=\"4a88996\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u00c0 l\u2019occasion de la <strong>Saint-Valentin<\/strong>, on vous propose des id\u00e9es de s\u00e9ries romantiques \u00e0 regarder en cette p\u00e9riode amoureuse, seul ou en amoureux ! \u2764\ufe0f<\/p><p>Premi\u00e8rement, on vous conseille La <strong>Chronique des Bridgerton<\/strong>, disponible sur Netflix. La s\u00e9rie est une adaptation du best-seller de Julia Quinn, qui se d\u00e9roule dans le Londres froufroutant de la R\u00e9gence. Les huit enfants de la fratrie unie des Bridgerton cherchent l&rsquo;amour et le bonheur dans la haute soci\u00e9t\u00e9 londonienne \ud83c\uddec\ud83c\udde7<\/p><p>Quittons maintenant les froufrous et les rubans de la <strong>Chronique de Bridgerton<\/strong> pour l\u2019\u00c9cosse avec la s\u00e9rie <strong>Outlander<\/strong>, o\u00f9 Claire, jeune Anglaise des ann\u00e9es 1940, est propuls\u00e9e dans le pass\u00e9 gr\u00e2ce \u00e0 la magie des menhirs. Dans un monde qui lui est compl\u00e8tement inconnu, elle devra survivre face \u00e0 la sauvagerie d\u2019une \u00e9poque et cacher son identit\u00e9. Mari\u00e9e de force \u00e0 Jamie Fraser, un \u00e9cossais rebelle, elle finira par s\u2019\u00e9prendre de cette nouvelle vie et de l\u2019homme qui saura la prot\u00e9ger des nombreux dangers qui la guettent.<\/p><p>Pour finir sur cet article, nous vous conseillons la s\u00e9rie <strong>Love &amp; Anarchy<\/strong>. Il s\u2019agit d\u2019une com\u00e9die dramatique su\u00e9doise en 8 \u00e9pisodes qui met en sc\u00e8ne un jeu du chat et de la souris hilarant et dangereux entre deux personnages que tout oppose. Une certaine complicit\u00e9 s\u2019installe entre les deux et leur jeu de s\u00e9duction va les pousser \u00e0 se lancer des d\u00e9fis de plus en plus audacieux qui vont les rapprocher.<\/p><p>Ces s\u00e9ries sont bien \u00e9videmment \u00e0 accompagner d\u2019un bon chocolat chaud \u2615<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-203f3d1 elementor-share-buttons--view-icon elementor-share-buttons--shape-circle elementor-share-buttons--skin-gradient elementor-grid-0 elementor-share-buttons--color-official elementor-widget elementor-widget-share-buttons\" data-id=\"203f3d1\" data-element_type=\"widget\" data-widget_type=\"share-buttons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_facebook\" role=\"button\" tabindex=\"0\" aria-label=\"Share on facebook\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-facebook\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_linkedin\" role=\"button\" tabindex=\"0\" aria-label=\"Share on linkedin\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-linkedin\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e9bb9f5 elementor-align-center elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"e9bb9f5\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"https:\/\/chloro-fil.fr\/lesnidsdechlorofil\/actualites\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">RETOUR<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u00c0 l\u2019occasion de la Saint-Valentin, on vous propose des id\u00e9es de s\u00e9ries romantiques \u00e0 regarder en cette p\u00e9riode amoureuse, seul ou en amoureux ! \u2764\ufe0f Premi\u00e8rement, on vous conseille La Chronique des Bridgerton, disponible sur Netflix. La s\u00e9rie est une adaptation du best-seller de Julia Quinn, qui se d\u00e9roule dans le Londres froufroutant de la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2236,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"elementor_header_footer","format":"standard","meta":{"_seopress_robots_primary_cat":"none","_seopress_titles_title":"Quoi regarder au chaud sous la couette ? | Les Nids de Chlorofil","_seopress_titles_desc":"\u00c0 l\u2019occasion de la Saint-Valentin, on vous propose des id\u00e9es de s\u00e9ries romantiques \u00e0 regarder en cette p\u00e9riode amoureuse, seul ou en amoureux ! \u2764\ufe0f","_seopress_robots_index":"","_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2235","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe"],"jetpack_featured_media_url":"https:\/\/chloro-fil.fr\/lesnidsdechlorofil\/wp-content\/uploads\/2021\/12\/saint-valentine-lesnids-chlorofil.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/chloro-fil.fr\/lesnidsdechlorofil\/wp-json\/wp\/v2\/posts\/2235","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chloro-fil.fr\/lesnidsdechlorofil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chloro-fil.fr\/lesnidsdechlorofil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chloro-fil.fr\/lesnidsdechlorofil\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/chloro-fil.fr\/lesnidsdechlorofil\/wp-json\/wp\/v2\/comments?post=2235"}],"version-history":[{"count":5,"href":"https:\/\/chloro-fil.fr\/lesnidsdechlorofil\/wp-json\/wp\/v2\/posts\/2235\/revisions"}],"predecessor-version":[{"id":2241,"href":"https:\/\/chloro-fil.fr\/lesnidsdechlorofil\/wp-json\/wp\/v2\/posts\/2235\/revisions\/2241"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chloro-fil.fr\/lesnidsdechlorofil\/wp-json\/wp\/v2\/media\/2236"}],"wp:attachment":[{"href":"https:\/\/chloro-fil.fr\/lesnidsdechlorofil\/wp-json\/wp\/v2\/media?parent=2235"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chloro-fil.fr\/lesnidsdechlorofil\/wp-json\/wp\/v2\/categories?post=2235"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chloro-fil.fr\/lesnidsdechlorofil\/wp-json\/wp\/v2\/tags?post=2235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}